{"id":2355,"date":"2015-02-09T15:47:46","date_gmt":"2015-02-09T17:47:46","guid":{"rendered":"http:\/\/www.abesata.org\/?p=2355"},"modified":"2015-02-09T15:47:46","modified_gmt":"2015-02-09T17:47:46","slug":"azul-adota-servico-de-atendimento-remoto-de-emergencia","status":"publish","type":"post","link":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/","title":{"rendered":"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia"},"content":{"rendered":"<div class=\"txt-body\"><a href=\"http:\/\/www.abesata.org\/wp-content\/uploads\/2015\/02\/azul090215.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-medium wp-image-2356 alignleft\" src=\"https:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-300x179.jpg\" alt=\"azul090215\" width=\"300\" height=\"179\" srcset=\"https:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-300x179.jpg 300w, https:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-250x150.jpg 250w, https:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-150x90.jpg 150w, https:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215.jpg 670w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<div class=\"row\">\n<div id=\"spacer-author\">\u00a0A Azul Linhas A\u00e9reas Brasileiras anunciou que todos os voos da companhia possuem agora um servi\u00e7o de atendimento remoto de emerg\u00eancia. \u00c9 o Med Link, tecnologia oferecida pela empresa norte-americana Med Aire que permite contato direto, via sat\u00e9lite, entre tripula\u00e7\u00e3o e profissionais da \u00e1rea de sa\u00fade, em caso de ocorr\u00eancia m\u00e9dica a bordo.<\/p>\n<p>\u201cSeguran\u00e7a \u00e9 um dos valores primordiais da Azul. Com o Med Link, poderemos aprimorar ainda mais este aspecto, tanto para nossos clientes quanto para nossas opera\u00e7\u00f5es de uma forma geral. \u00c9 importante ressaltar que o MedLink recomenda a\u00e7\u00f5es, n\u00e3o obriga. A decis\u00e3o final sobre alternar um voo, por exemplo, \u00e9 sempre do comandante\u201d, afirma o vice-presidente T\u00e9cnico-Operacional da Azul, Fl\u00e1vio Costa.<\/p>\n<p>Al\u00e9m das orienta\u00e7\u00f5es m\u00e9dicas, a equipe do Med Link pode recomendar outras a\u00e7\u00f5es, como pousos alternados para atendimento ao cliente. O novo servi\u00e7o tamb\u00e9m faz o rastreamento completo de hospitais e unidades de sa\u00fade em todas as cidades onde a Azul opera \u2013 no Brasil e no Exterior.<\/p>\n<p>O servi\u00e7o tamb\u00e9m est\u00e1 dispon\u00edvel nos port\u00f5es de embarque em todos os aeroportos onde a Azul opera. Desta forma, os agentes de aeroporto poder\u00e3o consultar os profissionais m\u00e9dicos para recomenda\u00e7\u00f5es em caso de eventos s\u00fabitos, como um cliente em condi\u00e7\u00e3o de sa\u00fade considerada inst\u00e1vel que se apresenta para embarque.<\/p><\/div>\n<div><\/div>\n<div>Fonte: Portal Panrotas<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0A Azul Linhas A\u00e9reas Brasileiras anunciou que todos os voos da companhia possuem agora um servi\u00e7o de atendimento remoto de emerg\u00eancia. \u00c9 o Med Link, tecnologia oferecida pela empresa norte-americana Med Aire que permite contato direto, via sat\u00e9lite, entre tripula\u00e7\u00e3o e profissionais da \u00e1rea de sa\u00fade, em caso de ocorr\u00eancia m\u00e9dica a bordo. \u201cSeguran\u00e7a \u00e9 [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-2355","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia - Abesata<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia - Abesata\" \/>\n<meta property=\"og:description\" content=\"\u00a0A Azul Linhas A\u00e9reas Brasileiras anunciou que todos os voos da companhia possuem agora um servi\u00e7o de atendimento remoto de emerg\u00eancia. \u00c9 o Med Link, tecnologia oferecida pela empresa norte-americana Med Aire que permite contato direto, via sat\u00e9lite, entre tripula\u00e7\u00e3o e profissionais da \u00e1rea de sa\u00fade, em caso de ocorr\u00eancia m\u00e9dica a bordo. \u201cSeguran\u00e7a \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Abesata\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abesata.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-09T17:47:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-300x179.jpg\" \/>\n<meta name=\"author\" content=\"Ricardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/\"},\"author\":{\"name\":\"Ricardo\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#\\\/schema\\\/person\\\/1f1295145bee68e42ffe39157320456b\"},\"headline\":\"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia\",\"datePublished\":\"2015-02-09T17:47:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abesata.org\\\/br\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/azul090215-300x179.jpg\",\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/\",\"url\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/\",\"name\":\"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia - Abesata\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abesata.org\\\/br\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/azul090215-300x179.jpg\",\"datePublished\":\"2015-02-09T17:47:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abesata.org\\\/br\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/azul090215-300x179.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abesata.org\\\/br\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/azul090215-300x179.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/azul-adota-servico-de-atendimento-remoto-de-emergencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/\",\"name\":\"Abesata\",\"description\":\"Associa\u00e7\u00e3o Brasileira das Empresas de Servi\u00e7os Auxiliares de Transporte A\u00e9reo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#organization\",\"name\":\"Associa\u00e7\u00e3o Brasileira das Empresas de Servi\u00e7os Auxiliares de Transporte A\u00e9reo\",\"alternateName\":\"Abesata\",\"url\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Abesata.png\",\"contentUrl\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Abesata.png\",\"width\":1063,\"height\":591,\"caption\":\"Associa\u00e7\u00e3o Brasileira das Empresas de Servi\u00e7os Auxiliares de Transporte A\u00e9reo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/abesata.org\\\/\",\"https:\\\/\\\/www.instagram.com\\\/abesata_gh\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/company\\\/abesata\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/#\\\/schema\\\/person\\\/1f1295145bee68e42ffe39157320456b\",\"name\":\"Ricardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d856797eb89513dee321f840c1a6bbcec15beb178c003e50adcf59323b3a8a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d856797eb89513dee321f840c1a6bbcec15beb178c003e50adcf59323b3a8a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d856797eb89513dee321f840c1a6bbcec15beb178c003e50adcf59323b3a8a9?s=96&d=mm&r=g\",\"caption\":\"Ricardo\"},\"url\":\"https:\\\/\\\/www.abesata.org\\\/br\\\/author\\\/ricardo-baroni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia - Abesata","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia - Abesata","og_description":"\u00a0A Azul Linhas A\u00e9reas Brasileiras anunciou que todos os voos da companhia possuem agora um servi\u00e7o de atendimento remoto de emerg\u00eancia. \u00c9 o Med Link, tecnologia oferecida pela empresa norte-americana Med Aire que permite contato direto, via sat\u00e9lite, entre tripula\u00e7\u00e3o e profissionais da \u00e1rea de sa\u00fade, em caso de ocorr\u00eancia m\u00e9dica a bordo. \u201cSeguran\u00e7a \u00e9 [&hellip;]","og_url":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/","og_site_name":"Abesata","article_publisher":"https:\/\/www.facebook.com\/abesata.org\/","article_published_time":"2015-02-09T17:47:46+00:00","og_image":[{"url":"http:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-300x179.jpg","type":"","width":"","height":""}],"author":"Ricardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ricardo","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/#article","isPartOf":{"@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/"},"author":{"name":"Ricardo","@id":"https:\/\/www.abesata.org\/br\/#\/schema\/person\/1f1295145bee68e42ffe39157320456b"},"headline":"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia","datePublished":"2015-02-09T17:47:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/"},"wordCount":252,"publisher":{"@id":"https:\/\/www.abesata.org\/br\/#organization"},"image":{"@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-300x179.jpg","inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/","url":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/","name":"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia - Abesata","isPartOf":{"@id":"https:\/\/www.abesata.org\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/#primaryimage"},"image":{"@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-300x179.jpg","datePublished":"2015-02-09T17:47:46+00:00","breadcrumb":{"@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/#primaryimage","url":"http:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-300x179.jpg","contentUrl":"http:\/\/www.abesata.org\/br\/wp-content\/uploads\/2015\/02\/azul090215-300x179.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.abesata.org\/br\/azul-adota-servico-de-atendimento-remoto-de-emergencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.abesata.org\/br\/"},{"@type":"ListItem","position":2,"name":"Azul adota servi\u00e7o de atendimento remoto de emerg\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.abesata.org\/br\/#website","url":"https:\/\/www.abesata.org\/br\/","name":"Abesata","description":"Associa\u00e7\u00e3o Brasileira das Empresas de Servi\u00e7os Auxiliares de Transporte A\u00e9reo","publisher":{"@id":"https:\/\/www.abesata.org\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abesata.org\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.abesata.org\/br\/#organization","name":"Associa\u00e7\u00e3o Brasileira das Empresas de Servi\u00e7os Auxiliares de Transporte A\u00e9reo","alternateName":"Abesata","url":"https:\/\/www.abesata.org\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.abesata.org\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www.abesata.org\/br\/wp-content\/uploads\/2023\/10\/Abesata.png","contentUrl":"https:\/\/www.abesata.org\/br\/wp-content\/uploads\/2023\/10\/Abesata.png","width":1063,"height":591,"caption":"Associa\u00e7\u00e3o Brasileira das Empresas de Servi\u00e7os Auxiliares de Transporte A\u00e9reo"},"image":{"@id":"https:\/\/www.abesata.org\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/abesata.org\/","https:\/\/www.instagram.com\/abesata_gh\/","https:\/\/br.linkedin.com\/company\/abesata"]},{"@type":"Person","@id":"https:\/\/www.abesata.org\/br\/#\/schema\/person\/1f1295145bee68e42ffe39157320456b","name":"Ricardo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1d856797eb89513dee321f840c1a6bbcec15beb178c003e50adcf59323b3a8a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d856797eb89513dee321f840c1a6bbcec15beb178c003e50adcf59323b3a8a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d856797eb89513dee321f840c1a6bbcec15beb178c003e50adcf59323b3a8a9?s=96&d=mm&r=g","caption":"Ricardo"},"url":"https:\/\/www.abesata.org\/br\/author\/ricardo-baroni\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/posts\/2355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/comments?post=2355"}],"version-history":[{"count":0,"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/posts\/2355\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/media?parent=2355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/categories?post=2355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abesata.org\/br\/wp-json\/wp\/v2\/tags?post=2355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}